{"id":14194,"date":"2025-10-08T15:18:24","date_gmt":"2025-10-08T15:18:24","guid":{"rendered":"https:\/\/www.wfsitalia.com\/?page_id=14194"},"modified":"2026-06-04T11:57:13","modified_gmt":"2026-06-04T09:57:13","slug":"tecnologia","status":"publish","type":"page","link":"https:\/\/wfsinc.com\/it\/tecnologia\/","title":{"rendered":"La nostra tecnologia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14194\" class=\"elementor elementor-14194\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d75b06 e-flex e-con-boxed e-con e-parent\" data-id=\"1d75b06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07b582d elementor-widget elementor-widget-heading\" data-id=\"07b582d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nostra strada verso le emissioni vicine allo zero<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-731076b elementor-widget elementor-widget-text-editor\" data-id=\"731076b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti, con un percorso verso emissioni (quasi) zero. Per questo, i nostri team di Ricerca e Sviluppo in tutto il mondo lavorano per ottimizzare componenti e sistemi per e con i nostri clienti (OEM , D-OEM e AfterMarket ).<\/p><p>Prestazioni , efficienza , economicit\u00e0 e sicurezza sono importanti nel rispetto dei pi\u00f9 severi standard sulle emissioni.<\/p><p>Le nostre tecnologie possono coprire due principali architetture di motori per sistemi di alimentazione, coprendo tutte le attuali tecnologie di motori disponibili sul mercato:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1f2678 e-flex e-con-boxed e-con e-parent\" data-id=\"d1f2678\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b7edd24 e-con-full e-flex e-con e-child\" data-id=\"b7edd24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa287cb elementor-widget elementor-widget-text-editor\" data-id=\"fa287cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Sistema primario<\/h4>\ndove il sistema di controllo WFS funziona in modo autonomo e controlla tutte le funzioni del motore\n<ul>\n \t<li>Motori da 1 a 6 cilindri<\/li>\n \t<li>Monocarburante e bicarburante<\/li>\n \t<li>CNG-GPL-Idrogeno<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c519a1 e-con-full e-flex e-con e-child\" data-id=\"6c519a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-087650b elementor-widget elementor-widget-text-editor\" data-id=\"087650b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Sistema secondario<\/h4>\n<p>in cui il sistema di controllo WFS funziona come aggiunta al sistema di gestione del motore originale e controlla la gestione del carburante alternativo:<\/p>\n<ul>\n<li>Motori a benzina da 1 a 10 cilindri<\/li>\n<li>GDI, PFI, Ibrido (da mild a plug-in)<\/li>\n<li>Tecnologia a doppio carburante sui motori diesel<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be3d487 e-flex e-con-boxed e-con e-parent\" data-id=\"be3d487\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5f596b6 e-con-full e-flex e-con e-child\" data-id=\"5f596b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5390bc2 elementor-widget elementor-widget-heading\" data-id=\"5390bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">AFC-3.0<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10324bc elementor-widget elementor-widget-text-editor\" data-id=\"10324bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La nostra <strong>ultima centralina AFC-3.0 DI<\/strong> pu\u00f2 essere programmata in base al sistema di gestione di ciascun veicolo e di ciascun motore a benzina, utilizzando un&#8217;elettronica con tecnologia ibrida avanzata.<\/p><p>Il nostro hardware di iniezione e il nostro esclusivo riduttore eVP-500 garantiscono un&#8217;erogazione precisa del carburante in ogni condizione operativa del motore. La combinazione di questi componenti all&#8217;avanguardia garantisce un sistema di alimentazione dalle prestazioni ottimali, con prestazioni ed efficienza senza pari.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50bef92 e-con-full e-flex e-con e-child\" data-id=\"50bef92\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27877bb elementor-widget elementor-widget-image\" data-id=\"27877bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"669\" src=\"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800-1024x878.jpg\" class=\"attachment-large size-large wp-image-14206\" alt=\"\" srcset=\"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800-1024x878.jpg 1024w, https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800-300x257.jpg 300w, https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800.jpg 1125w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c4dd6a e-flex e-con-boxed e-con e-parent\" data-id=\"4c4dd6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f70836d e-con-full e-flex e-con e-child\" data-id=\"f70836d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71ffd9f elementor-widget elementor-widget-heading\" data-id=\"71ffd9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La  tecnologia Dual Fuel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88f56d7 elementor-widget elementor-widget-text-editor\" data-id=\"88f56d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La tecnologia <strong>Dual Fuel<\/strong> pu\u00f2 essere utilizzata in tutto il mondo per veicoli stradali e fuoristrada, motori diesel marini e stazionari, ovunque siano disponibili carburanti alternativi. Viene utilizzata principalmente per veicoli pesanti. La tecnologia Dual Fuel si basa sull&#8217;utilizzo di due carburanti diversi in un motore diesel ad accensione per compressione (CI). In questo modo, una parte del gasolio pu\u00f2 essere sostituita da un carburante alternativo pi\u00f9 pulito ed economico. Il gasolio rimane responsabile dell&#8217;accensione. Il carburante secondario \u00e8 un carburante alternativo come GPL, CNG, GNL o H2.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3938bd e-con-full e-flex e-con e-child\" data-id=\"d3938bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35e2685 elementor-widget elementor-widget-image\" data-id=\"35e2685\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"760\" height=\"505\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&apos;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&apos; viewBox%3D&apos;0 0 760 505&apos;%2F%3E\" class=\"attachment-large size-large wp-image-14208 ld-lazyload\" alt=\"\" data-src=\"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/Engine-D1386_w800.jpg\" data-srcset=\"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/Engine-D1386_w800.jpg 760w, https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/Engine-D1386_w800-300x199.jpg 300w\" data-sizes=\"(max-width: 760px) 100vw, 760px\" data-aspect=\"1.5049504950495\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f66281f e-flex e-con-boxed e-con e-parent\" data-id=\"f66281f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4531a8 elementor-widget elementor-widget-heading\" data-id=\"c4531a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tecnologia ibrida<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32254d5 elementor-widget elementor-widget-text-editor\" data-id=\"32254d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Insieme a KIA Italia, abbiamo sviluppato la nuova <strong>Kia Niro Tri-Fuel<\/strong>, il primo veicolo ibrido OEM alimentato da HEV e GPL utilizzando 3 &#8220;fonti di carburante&#8221;: benzina, elettrico e GPL.<br \/><br \/>I nostri kit aftermarket possono coprire anche i veicoli ibridi plug-in.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e67350d e-flex e-con-boxed e-con e-parent\" data-id=\"e67350d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a56faf elementor-widget elementor-widget-heading\" data-id=\"1a56faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Idrogeno e energie rinnovabili<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3367208 elementor-widget elementor-widget-text-editor\" data-id=\"3367208\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOggi stiamo gi\u00e0 lavorando a soluzioni che utilizzano altri combustibili alternativi, come biocarburanti, idrogeno e DME. Collaboriamo con stakeholder chiave come governi, fornitori e produttori di carburante, universit\u00e0 e OEM e  crediamo  che i nostri prodotti rappresenteranno una tecnologia importante nel nostro percorso verso un futuro pi\u00f9 verde nei trasporti.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a22a52 e-flex e-con-boxed e-con e-parent\" data-id=\"1a22a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81b216a elementor-widget elementor-widget-text-editor\" data-id=\"81b216a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOgni mercato mondiale ha esigenze specifiche e pertanto i nostri team collaborano con i clienti locali per ottimizzare i sistemi. Consultate i siti web dei nostri marchi per informazioni specifiche e seguite le nostre news per rimanere aggiornati sugli ultimi sviluppi.  \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44a4ad9 e-flex e-con-boxed e-con e-parent\" data-id=\"44a4ad9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcd746a elementor-widget elementor-widget-text-editor\" data-id=\"bcd746a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSe desiderate maggiori informazioni su determinate tecnologie o soluzioni complete, contattateci via email: <strong>info@wfsinc.com<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La nostra strada verso le emissioni vicine allo zero Le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti, con un percorso verso emissioni (quasi) zero. Per questo, i nostri team di Ricerca e Sviluppo in tutto il mondo lavorano per ottimizzare componenti e sistemi per [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-14194","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Westport Fuel Systems | La nostra Tecnologia<\/title>\n<meta name=\"description\" content=\"Scopri come le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wfsinc.com\/it\/tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Westport Fuel Systems | La nostra Tecnologia\" \/>\n<meta property=\"og:description\" content=\"Scopri come le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wfsinc.com\/it\/tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"WFS Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T09:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800.jpg?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"965\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/\",\"url\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/\",\"name\":\"Westport Fuel Systems | La nostra Tecnologia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wfsinc.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WFS21_w800-1024x878.jpg\",\"datePublished\":\"2025-10-08T15:18:24+00:00\",\"dateModified\":\"2026-06-04T09:57:13+00:00\",\"description\":\"Scopri come le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wfsinc.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WFS21_w800-1024x878.jpg\",\"contentUrl\":\"https:\\\/\\\/wfsinc.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WFS21_w800-1024x878.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/tecnologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nostra tecnologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/\",\"name\":\"WFS Italia\",\"description\":\"Westport Fuel Systems Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wfsinc.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Westport Fuel Systems | La nostra Tecnologia","description":"Scopri come le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wfsinc.com\/it\/tecnologia\/","og_locale":"it_IT","og_type":"article","og_title":"Westport Fuel Systems | La nostra Tecnologia","og_description":"Scopri come le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti.","og_url":"https:\/\/wfsinc.com\/it\/tecnologia\/","og_site_name":"WFS Italia","article_modified_time":"2026-06-04T09:57:13+00:00","og_image":[{"width":1125,"height":965,"url":"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800.jpg?wsr","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wfsinc.com\/it\/tecnologia\/","url":"https:\/\/wfsinc.com\/it\/tecnologia\/","name":"Westport Fuel Systems | La nostra Tecnologia","isPartOf":{"@id":"https:\/\/wfsinc.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wfsinc.com\/it\/tecnologia\/#primaryimage"},"image":{"@id":"https:\/\/wfsinc.com\/it\/tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800-1024x878.jpg","datePublished":"2025-10-08T15:18:24+00:00","dateModified":"2026-06-04T09:57:13+00:00","description":"Scopri come le nostre tecnologie per i carburanti alternativi si concentrano su una mobilit\u00e0 e un trasporto innovativi e pi\u00f9 puliti.","breadcrumb":{"@id":"https:\/\/wfsinc.com\/it\/tecnologia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wfsinc.com\/it\/tecnologia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wfsinc.com\/it\/tecnologia\/#primaryimage","url":"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800-1024x878.jpg","contentUrl":"https:\/\/wfsinc.com\/wp-content\/uploads\/2025\/10\/WFS21_w800-1024x878.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/wfsinc.com\/it\/tecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wfsinc.com\/it\/"},{"@type":"ListItem","position":2,"name":"La nostra tecnologia"}]},{"@type":"WebSite","@id":"https:\/\/wfsinc.com\/it\/#website","url":"https:\/\/wfsinc.com\/it\/","name":"WFS Italia","description":"Westport Fuel Systems Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wfsinc.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/pages\/14194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/comments?post=14194"}],"version-history":[{"count":73,"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/pages\/14194\/revisions"}],"predecessor-version":[{"id":18608,"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/pages\/14194\/revisions\/18608"}],"wp:attachment":[{"href":"https:\/\/wfsinc.com\/it\/wp-json\/wp\/v2\/media?parent=14194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}